{"id":2915,"date":"2025-12-24T17:43:27","date_gmt":"2025-12-24T16:43:27","guid":{"rendered":"https:\/\/foodstory.es\/?p=2915"},"modified":"2025-12-24T17:43:31","modified_gmt":"2025-12-24T16:43:31","slug":"la-generacion-alfa-y-la-moda-6-7-vuelve-locos-los-cmo-de-las-cadenas-de-restaurantes","status":"publish","type":"post","link":"https:\/\/foodstory.es\/en\/la-generacion-alfa-y-la-moda-6-7-vuelve-locos-los-cmo-de-las-cadenas-de-restaurantes\/","title":{"rendered":"La generaci\u00f3n alfa y la moda 6-7 vuelve locos  los CMO de las cadenas de restaurantes"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Cadenas como Chick\u00b4fil-A, Wendy\u00b4s Pizza Hut  se han visto en la necesidad de reformular sus planes de mkt cuando la generaci\u00f3n alfa(2013-2014) se ha puesto a comprar todo lo que lleva el sello o mensaje 6\/7 ; en especial desde que la singer Sophie James subio a Tik Tok siete videos de los cuales el 7 fue el que tuvo m\u00e1s aceptaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y es que se calcula que ese nuevo colectivo, entre 4 y 18 a\u00f1os, visita Tik Tok durante 112m al dia, por lo que no es de extra\u00f1ar que esos d\u00edgitos, que puede que pusieran de moda el rapero Skrilla con su cancion Doot Doot 6\/7 o el basketmen de la NBA LaMelo Bull que mide 6pies y 7 pulgadas, supla cualquier campa\u00f1a al uso.<\/p>","protected":false},"excerpt":{"rendered":"<p>Cadenas como Chick\u00b4fil-A, Wendy\u00b4s Pizza Hut se han visto en la necesidad de reformular sus planes de mkt cuando la generaci\u00f3n alfa(2013-2014) se ha puesto a comprar todo lo que lleva el sello o mensaje 6\/7 ; en especial desde que la&#8230;<\/p>","protected":false},"author":1,"featured_media":2916,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[1,7],"tags":[],"class_list":["post-2915","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-restauracion-comercial"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La generaci\u00f3n alfa y la moda 6-7 vuelve locos los CMO de las cadenas de restaurantes - Food Story<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/foodstory.es\/en\/la-generacion-alfa-y-la-moda-6-7-vuelve-locos-los-cmo-de-las-cadenas-de-restaurantes\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La generaci\u00f3n alfa y la moda 6-7 vuelve locos los CMO de las cadenas de restaurantes - Food Story\" \/>\n<meta property=\"og:description\" content=\"Cadenas como Chick\u00b4fil-A, Wendy\u00b4s Pizza Hut se han visto en la necesidad de reformular sus planes de mkt cuando la generaci\u00f3n alfa(2013-2014) se ha puesto a comprar todo lo que lleva el sello o mensaje 6\/7 ; en especial desde que la...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/foodstory.es\/en\/la-generacion-alfa-y-la-moda-6-7-vuelve-locos-los-cmo-de-las-cadenas-de-restaurantes\/\" \/>\n<meta property=\"og:site_name\" content=\"Food Story\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-24T16:43:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-24T16:43:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/foodstory.es\/wp-content\/uploads\/2025\/12\/logo-6-7-.png\" \/>\n\t<meta property=\"og:image:width\" content=\"210\" \/>\n\t<meta property=\"og:image:height\" content=\"106\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"eloi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"eloi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/foodstory.es\\\/la-generacion-alfa-y-la-moda-6-7-vuelve-locos-los-cmo-de-las-cadenas-de-restaurantes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/foodstory.es\\\/la-generacion-alfa-y-la-moda-6-7-vuelve-locos-los-cmo-de-las-cadenas-de-restaurantes\\\/\"},\"author\":{\"name\":\"eloi\",\"@id\":\"https:\\\/\\\/foodstory.es\\\/#\\\/schema\\\/person\\\/9f90bee5e60ba1bf8d3f286132644e1e\"},\"headline\":\"La generaci\u00f3n alfa y la moda 6-7 vuelve locos los CMO de las cadenas de restaurantes\",\"datePublished\":\"2025-12-24T16:43:27+00:00\",\"dateModified\":\"2025-12-24T16:43:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/foodstory.es\\\/la-generacion-alfa-y-la-moda-6-7-vuelve-locos-los-cmo-de-las-cadenas-de-restaurantes\\\/\"},\"wordCount\":147,\"publisher\":{\"@id\":\"https:\\\/\\\/foodstory.es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/foodstory.es\\\/la-generacion-alfa-y-la-moda-6-7-vuelve-locos-los-cmo-de-las-cadenas-de-restaurantes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/foodstory.es\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/logo-6-7-.png\",\"articleSection\":[\"ACTUALIDAD\",\"RESTAURACI\u00d3N COMERCIAL\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/foodstory.es\\\/la-generacion-alfa-y-la-moda-6-7-vuelve-locos-los-cmo-de-las-cadenas-de-restaurantes\\\/\",\"url\":\"https:\\\/\\\/foodstory.es\\\/la-generacion-alfa-y-la-moda-6-7-vuelve-locos-los-cmo-de-las-cadenas-de-restaurantes\\\/\",\"name\":\"La generaci\u00f3n alfa y la moda 6-7 vuelve locos los CMO de las cadenas de restaurantes - Food Story\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/foodstory.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/foodstory.es\\\/la-generacion-alfa-y-la-moda-6-7-vuelve-locos-los-cmo-de-las-cadenas-de-restaurantes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/foodstory.es\\\/la-generacion-alfa-y-la-moda-6-7-vuelve-locos-los-cmo-de-las-cadenas-de-restaurantes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/foodstory.es\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/logo-6-7-.png\",\"datePublished\":\"2025-12-24T16:43:27+00:00\",\"dateModified\":\"2025-12-24T16:43:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/foodstory.es\\\/la-generacion-alfa-y-la-moda-6-7-vuelve-locos-los-cmo-de-las-cadenas-de-restaurantes\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/foodstory.es\\\/la-generacion-alfa-y-la-moda-6-7-vuelve-locos-los-cmo-de-las-cadenas-de-restaurantes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/foodstory.es\\\/la-generacion-alfa-y-la-moda-6-7-vuelve-locos-los-cmo-de-las-cadenas-de-restaurantes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/foodstory.es\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/logo-6-7-.png\",\"contentUrl\":\"https:\\\/\\\/foodstory.es\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/logo-6-7-.png\",\"width\":210,\"height\":106},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/foodstory.es\\\/la-generacion-alfa-y-la-moda-6-7-vuelve-locos-los-cmo-de-las-cadenas-de-restaurantes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/foodstory.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La generaci\u00f3n alfa y la moda 6-7 vuelve locos los CMO de las cadenas de restaurantes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/foodstory.es\\\/#website\",\"url\":\"https:\\\/\\\/foodstory.es\\\/\",\"name\":\"Food Story\",\"description\":\"Visionando el futuro sin olvidar el pasado\",\"publisher\":{\"@id\":\"https:\\\/\\\/foodstory.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/foodstory.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/foodstory.es\\\/#organization\",\"name\":\"Food Story\",\"url\":\"https:\\\/\\\/foodstory.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/foodstory.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/foodstory.es\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/LOGO-Food-Story.png\",\"contentUrl\":\"https:\\\/\\\/foodstory.es\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/LOGO-Food-Story.png\",\"width\":800,\"height\":800,\"caption\":\"Food Story\"},\"image\":{\"@id\":\"https:\\\/\\\/foodstory.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/foodstory.es\\\/#\\\/schema\\\/person\\\/9f90bee5e60ba1bf8d3f286132644e1e\",\"name\":\"eloi\",\"sameAs\":[\"http:\\\/\\\/foodstory.es\"],\"url\":\"https:\\\/\\\/foodstory.es\\\/en\\\/author\\\/eloi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La generaci\u00f3n alfa y la moda 6-7 vuelve locos los CMO de las cadenas de restaurantes - Food Story","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/foodstory.es\/en\/la-generacion-alfa-y-la-moda-6-7-vuelve-locos-los-cmo-de-las-cadenas-de-restaurantes\/","og_locale":"en_GB","og_type":"article","og_title":"La generaci\u00f3n alfa y la moda 6-7 vuelve locos los CMO de las cadenas de restaurantes - Food Story","og_description":"Cadenas como Chick\u00b4fil-A, Wendy\u00b4s Pizza Hut se han visto en la necesidad de reformular sus planes de mkt cuando la generaci\u00f3n alfa(2013-2014) se ha puesto a comprar todo lo que lleva el sello o mensaje 6\/7 ; en especial desde que la...","og_url":"https:\/\/foodstory.es\/en\/la-generacion-alfa-y-la-moda-6-7-vuelve-locos-los-cmo-de-las-cadenas-de-restaurantes\/","og_site_name":"Food Story","article_published_time":"2025-12-24T16:43:27+00:00","article_modified_time":"2025-12-24T16:43:31+00:00","og_image":[{"width":210,"height":106,"url":"https:\/\/foodstory.es\/wp-content\/uploads\/2025\/12\/logo-6-7-.png","type":"image\/png"}],"author":"eloi","twitter_card":"summary_large_image","twitter_misc":{"Written by":"eloi","Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/foodstory.es\/la-generacion-alfa-y-la-moda-6-7-vuelve-locos-los-cmo-de-las-cadenas-de-restaurantes\/#article","isPartOf":{"@id":"https:\/\/foodstory.es\/la-generacion-alfa-y-la-moda-6-7-vuelve-locos-los-cmo-de-las-cadenas-de-restaurantes\/"},"author":{"name":"eloi","@id":"https:\/\/foodstory.es\/#\/schema\/person\/9f90bee5e60ba1bf8d3f286132644e1e"},"headline":"La generaci\u00f3n alfa y la moda 6-7 vuelve locos los CMO de las cadenas de restaurantes","datePublished":"2025-12-24T16:43:27+00:00","dateModified":"2025-12-24T16:43:31+00:00","mainEntityOfPage":{"@id":"https:\/\/foodstory.es\/la-generacion-alfa-y-la-moda-6-7-vuelve-locos-los-cmo-de-las-cadenas-de-restaurantes\/"},"wordCount":147,"publisher":{"@id":"https:\/\/foodstory.es\/#organization"},"image":{"@id":"https:\/\/foodstory.es\/la-generacion-alfa-y-la-moda-6-7-vuelve-locos-los-cmo-de-las-cadenas-de-restaurantes\/#primaryimage"},"thumbnailUrl":"https:\/\/foodstory.es\/wp-content\/uploads\/2025\/12\/logo-6-7-.png","articleSection":["ACTUALIDAD","RESTAURACI\u00d3N COMERCIAL"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/foodstory.es\/la-generacion-alfa-y-la-moda-6-7-vuelve-locos-los-cmo-de-las-cadenas-de-restaurantes\/","url":"https:\/\/foodstory.es\/la-generacion-alfa-y-la-moda-6-7-vuelve-locos-los-cmo-de-las-cadenas-de-restaurantes\/","name":"La generaci\u00f3n alfa y la moda 6-7 vuelve locos los CMO de las cadenas de restaurantes - Food Story","isPartOf":{"@id":"https:\/\/foodstory.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/foodstory.es\/la-generacion-alfa-y-la-moda-6-7-vuelve-locos-los-cmo-de-las-cadenas-de-restaurantes\/#primaryimage"},"image":{"@id":"https:\/\/foodstory.es\/la-generacion-alfa-y-la-moda-6-7-vuelve-locos-los-cmo-de-las-cadenas-de-restaurantes\/#primaryimage"},"thumbnailUrl":"https:\/\/foodstory.es\/wp-content\/uploads\/2025\/12\/logo-6-7-.png","datePublished":"2025-12-24T16:43:27+00:00","dateModified":"2025-12-24T16:43:31+00:00","breadcrumb":{"@id":"https:\/\/foodstory.es\/la-generacion-alfa-y-la-moda-6-7-vuelve-locos-los-cmo-de-las-cadenas-de-restaurantes\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/foodstory.es\/la-generacion-alfa-y-la-moda-6-7-vuelve-locos-los-cmo-de-las-cadenas-de-restaurantes\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/foodstory.es\/la-generacion-alfa-y-la-moda-6-7-vuelve-locos-los-cmo-de-las-cadenas-de-restaurantes\/#primaryimage","url":"https:\/\/foodstory.es\/wp-content\/uploads\/2025\/12\/logo-6-7-.png","contentUrl":"https:\/\/foodstory.es\/wp-content\/uploads\/2025\/12\/logo-6-7-.png","width":210,"height":106},{"@type":"BreadcrumbList","@id":"https:\/\/foodstory.es\/la-generacion-alfa-y-la-moda-6-7-vuelve-locos-los-cmo-de-las-cadenas-de-restaurantes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/foodstory.es\/"},{"@type":"ListItem","position":2,"name":"La generaci\u00f3n alfa y la moda 6-7 vuelve locos los CMO de las cadenas de restaurantes"}]},{"@type":"WebSite","@id":"https:\/\/foodstory.es\/#website","url":"https:\/\/foodstory.es\/","name":"Food Story","description":"Envisioning the future without forgetting the past","publisher":{"@id":"https:\/\/foodstory.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/foodstory.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/foodstory.es\/#organization","name":"Food Story","url":"https:\/\/foodstory.es\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/foodstory.es\/#\/schema\/logo\/image\/","url":"https:\/\/foodstory.es\/wp-content\/uploads\/2024\/01\/LOGO-Food-Story.png","contentUrl":"https:\/\/foodstory.es\/wp-content\/uploads\/2024\/01\/LOGO-Food-Story.png","width":800,"height":800,"caption":"Food Story"},"image":{"@id":"https:\/\/foodstory.es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/foodstory.es\/#\/schema\/person\/9f90bee5e60ba1bf8d3f286132644e1e","name":"eloi","sameAs":["http:\/\/foodstory.es"],"url":"https:\/\/foodstory.es\/en\/author\/eloi\/"}]}},"taxonomy_info":{"category":[{"value":1,"label":"ACTUALIDAD"},{"value":7,"label":"RESTAURACI\u00d3N COMERCIAL"}]},"featured_image_src_large":["https:\/\/foodstory.es\/wp-content\/uploads\/2025\/12\/logo-6-7-.png",210,106,false],"author_info":{"display_name":"eloi","author_link":"https:\/\/foodstory.es\/en\/author\/eloi\/"},"comment_info":0,"category_info":[{"term_id":1,"name":"ACTUALIDAD","slug":"actualidad","term_group":0,"term_taxonomy_id":1,"taxonomy":"category","description":"","parent":0,"count":140,"filter":"raw","term_order":"0","cat_ID":1,"category_count":140,"category_description":"","cat_name":"ACTUALIDAD","category_nicename":"actualidad","category_parent":0},{"term_id":7,"name":"RESTAURACI\u00d3N COMERCIAL","slug":"restauracion-comercial","term_group":0,"term_taxonomy_id":7,"taxonomy":"category","description":"","parent":0,"count":141,"filter":"raw","term_order":"0","cat_ID":7,"category_count":141,"category_description":"","cat_name":"RESTAURACI\u00d3N COMERCIAL","category_nicename":"restauracion-comercial","category_parent":0}],"tag_info":false,"_links":{"self":[{"href":"https:\/\/foodstory.es\/en\/wp-json\/wp\/v2\/posts\/2915","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/foodstory.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/foodstory.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/foodstory.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/foodstory.es\/en\/wp-json\/wp\/v2\/comments?post=2915"}],"version-history":[{"count":1,"href":"https:\/\/foodstory.es\/en\/wp-json\/wp\/v2\/posts\/2915\/revisions"}],"predecessor-version":[{"id":2917,"href":"https:\/\/foodstory.es\/en\/wp-json\/wp\/v2\/posts\/2915\/revisions\/2917"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/foodstory.es\/en\/wp-json\/wp\/v2\/media\/2916"}],"wp:attachment":[{"href":"https:\/\/foodstory.es\/en\/wp-json\/wp\/v2\/media?parent=2915"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/foodstory.es\/en\/wp-json\/wp\/v2\/categories?post=2915"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/foodstory.es\/en\/wp-json\/wp\/v2\/tags?post=2915"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}