{"id":3397,"date":"2026-09-01T18:50:06","date_gmt":"2026-09-01T16:50:06","guid":{"rendered":"https:\/\/foodstory.es\/?p=3397"},"modified":"2026-09-01T18:50:10","modified_gmt":"2026-09-01T16:50:10","slug":"el-culebron-sobre-la-fatidica-promocion-de-red-lobsteraun-colea","status":"publish","type":"post","link":"https:\/\/foodstory.es\/ca\/el-culebron-sobre-la-fatidica-promocion-de-red-lobsteraun-colea\/","title":{"rendered":"El culebr\u00f3n sobre la \u00a0fat\u00eddica promoci\u00f3n de Red Lobster,aun colea"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan&nbsp; Joe Guszkowski, redactor senior de Business Restaurant,el exaccionista de Red Lobster, Thai Union Group, afirma que no es responsable de la desastrosa promoci\u00f3n Ultimate Endless Shrimp de la cadena hace tres a\u00f1os.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En un documento judicial presentado la semana pasada, el proveedor tailand\u00e9s de mariscos argumenta que Red Lobster Management ide\u00f3 el acuerdo de pagar solo 20 d\u00f3lares &nbsp;por todo lo que pudieras &nbsp;comer para ayudar a mejorar el tr\u00e1fico, no para aumentar las ventas de gambas a Thai Union.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La presentaci\u00f3n de Thai Union se produce en respuesta a una demanda de junio presentada por GUC Trust, un grupo de acreedores de Red Lobster que acus\u00f3 a Thai Union y a una docena de otros acusados de conspirar para gestionar &nbsp;Red Lobster y comprar m\u00e1s gambas a Thai Union. Endless Shrimp, seg\u00fan la demanda, fue b\u00e1sica &nbsp;en ese plan.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La promoci\u00f3n &nbsp;sali\u00f3 muy mal, cost\u00e1ndole millones de d\u00f3lares &nbsp;a la empresa en el verano de 2023, ya que los clientes comieron a destajo . Red Lobster se declar\u00f3 en bancarrota aproximadamente un a\u00f1o despu\u00e9s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En su escrito, Thai Union solicita a un juez que desestime el caso, calific\u00e1ndolo como \u00abun intento c\u00ednico de Red Lobster de culpar a uno de sus antiguos propietarios y proveedores de los fallos en las propias decisiones de gesti\u00f3n y el modelo de negocio de Red Lobster.\u00bbSostiene que la demanda de los acreedores confunde a Thai Union con las acciones de otros demandados no relacionados, especialmente Paul Kenny, CEO interino de Red Lobster entre 2022 y 2023.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La demanda de los acreedores alega que Kenny trabaj\u00f3 en nombre de Thai Union para impulsar su negocio de gambas, incluyendo el &nbsp;bloqueo a otros proveedores y encargando el acuerdo Endless Shrimp.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Thai Union dice que Kenny trabaj\u00f3 para Seafood Alliance, una empresa independiente con participaci\u00f3n en Red Lobster, y que la decisi\u00f3n de Endless Shrimp fue solo suya. Seg\u00fan la demanda de los acreedores, Seafood Alliance fue creada por Thai Union y Kenny en 2020 para comprar m\u00e1s Red Lobster.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Thai Union tambi\u00e9n afirma que fue exonerada de mala conducta en Endless Shrimp en una investigaci\u00f3n anterior ordenada por los demandantes antes de la bancarrota de Red Lobster. La investigaci\u00f3n de Weil, Gotshal &amp; Manges concluy\u00f3 que \u00abno parec\u00eda haber ninguna reclamaci\u00f3n viable\u00bb contra Thai Union o sus responsables y que Endless Shrimp fue creado \u00abcon la intenci\u00f3n genuina de mejorar las perspectivas financieras de [Red Lobster].\u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Leigh Nathanson, socio de los abogados de los acreedores King &amp; Spalding, dijo que la moci\u00f3n de Thai Union solo aborda los hechos del caso, que deber\u00edan ser decididos por un jurado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abLa moci\u00f3n de Thai Union para desestimar disputa los hechos clave de este caso, incluyendo si Thai Union \u2014como mayor accionista y mayor proveedor de marisco\u2014 incumpli\u00f3 los derechos hacia Red Lobster cuando este cataliz\u00f3 las p\u00e9rdidas de Red Lobster para su propio beneficio\u00bb, dijo en un correo electr\u00f3nico. \u00abPero las disputas f\u00e1cticas, como el intento de Thai Union de distanciarse de las acciones del ex CEO designado por Thai Union, Paul Kenny, son para que lo decida un jurado y pueden no resolverse mediante una moci\u00f3n de desestimaci\u00f3n. Esperamos avanzar hacia el descubrimiento y demostrar la auto-explotaci\u00f3n y el negocio de Red Lobster para maximizar la recuperaci\u00f3n de los acreedores de Red Lobster.\u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Red Lobster declin\u00f3 comentar las afirmaciones de Thai Union.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La situaci\u00f3n se remonta a 2016, cuando Thai Union, proveedor de marisco desde hace mucho tiempo de Red Lobster, adquiri\u00f3 una participaci\u00f3n del 25% en la cadena. En 2020, Thai Union, Seafood Alliance y otras filiales adquirieron una participaci\u00f3n mayoritaria del anterior propietario Golden Gate Capital.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mientras Red Lobster luchaba con las consecuencias de la pandemia, Thai Union comenz\u00f3 a adoptar un enfoque m\u00e1s pr\u00e1ctico en la cadena. Los responsables del sindicato tailand\u00e9s visitaron restaurantes a finales de 2022 o principios de 2023, y Kenny fue nombrado CEO interino en agosto de 2022. Sustituy\u00f3 a Kelli Valade, que dimiti\u00f3 en abril de 2022 tras menos de un a\u00f1o en el cargo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En junio de 2023, bajo el liderazgo de Kenny, Red Lobster lanz\u00f3 la promoci\u00f3n &nbsp;Ultimate Endless Shrimp por 20 d\u00f3lares. Anteriormente era una oferta por tiempo limitado, pero el acuerdo pas\u00f3 a formar parte del men\u00fa permanente. Los clientes acudieron en masa a Red Lobster para aprovechar la ganga, lo que ayud\u00f3 al tr\u00e1fico pero finalmente llev\u00f3 a la empresa a perder 11 millones de d\u00f3lares ese trimestre. La cadena subi\u00f3 posteriormente el precio del acuerdo antes de cancelarlo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En septiembre, Kenny fue reemplazado como CEO por Horace Dawson, asesor jur\u00eddico general de Red Lobster.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En enero siguiente, Thai Union anunci\u00f3 planes para desinvertir en Red Lobster.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Red Lobster se declar\u00f3 en bancarrota en mayo de 2024, con unas deudas de unos 300 millones de d\u00f3lares, tras cerrar decenas de restaurantes en todo el pa\u00eds. Sali\u00f3 de la situaci\u00f3n ese septiembre mediante una venta a un grupo liderado por Fortress Investment Group.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Red Lobster cit\u00f3 m\u00faltiples razones para sus problemas financieros, pero la poco aconsejada promoci\u00f3n de gambas jug\u00f3 un papel. La actual directora ejecutiva, Damola Adamolekun, la ha calificado como \u00abel clavo final en el ata\u00fad\u00bb en la ca\u00edda de la cadena hacia la bancarrota.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La cadena ha estado trabajando en un regreso bajo Adamolekun, que ha incluido cambios en su carta y operaciones, as\u00ed como un plan para remodelar muchos de sus restaurantes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En abril, trajo de vuelta Endless Shrimp por primera vez desde 2023, pero por un tiempo limitado y a un precio m\u00e1s alto<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seg\u00fan&nbsp; Joe Guszkowski, redactor senior de Business Restaurant,el exaccionista de Red Lobster, Thai Union Group, afirma que no es responsable de la desastrosa promoci\u00f3n Ultimate Endless Shrimp de la cadena hace tres a\u00f1os. En un documento judicial presentado la semana pasada, el&#8230;<\/p>","protected":false},"author":1,"featured_media":1659,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[7],"tags":[],"class_list":["post-3397","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-restauracion-comercial"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El culebr\u00f3n sobre la \u00a0fat\u00eddica promoci\u00f3n de Red Lobster,aun colea - Food Story<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/foodstory.es\/ca\/el-culebron-sobre-la-fatidica-promocion-de-red-lobsteraun-colea\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El culebr\u00f3n sobre la \u00a0fat\u00eddica promoci\u00f3n de Red Lobster,aun colea - Food Story\" \/>\n<meta property=\"og:description\" content=\"Seg\u00fan&nbsp; Joe Guszkowski, redactor senior de Business Restaurant,el exaccionista de Red Lobster, Thai Union Group, afirma que no es responsable de la desastrosa promoci\u00f3n Ultimate Endless Shrimp de la cadena hace tres a\u00f1os. En un documento judicial presentado la semana pasada, el...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/foodstory.es\/ca\/el-culebron-sobre-la-fatidica-promocion-de-red-lobsteraun-colea\/\" \/>\n<meta property=\"og:site_name\" content=\"Food Story\" \/>\n<meta property=\"article:published_time\" content=\"2026-09-01T16:50:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-01T16:50:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/foodstory.es\/wp-content\/uploads\/2024\/06\/cartel-d-ered-lobster.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"767\" \/>\n\t<meta property=\"og:image:height\" content=\"420\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"eloi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"eloi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/foodstory.es\\\/el-culebron-sobre-la-fatidica-promocion-de-red-lobsteraun-colea\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/foodstory.es\\\/el-culebron-sobre-la-fatidica-promocion-de-red-lobsteraun-colea\\\/\"},\"author\":{\"name\":\"eloi\",\"@id\":\"https:\\\/\\\/foodstory.es\\\/#\\\/schema\\\/person\\\/9f90bee5e60ba1bf8d3f286132644e1e\"},\"headline\":\"El culebr\u00f3n sobre la \u00a0fat\u00eddica promoci\u00f3n de Red Lobster,aun colea\",\"datePublished\":\"2026-09-01T16:50:06+00:00\",\"dateModified\":\"2026-09-01T16:50:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/foodstory.es\\\/el-culebron-sobre-la-fatidica-promocion-de-red-lobsteraun-colea\\\/\"},\"wordCount\":980,\"publisher\":{\"@id\":\"https:\\\/\\\/foodstory.es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/foodstory.es\\\/el-culebron-sobre-la-fatidica-promocion-de-red-lobsteraun-colea\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/foodstory.es\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/cartel-d-ered-lobster.jpg\",\"articleSection\":[\"RESTAURACI\u00d3N COMERCIAL\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/foodstory.es\\\/el-culebron-sobre-la-fatidica-promocion-de-red-lobsteraun-colea\\\/\",\"url\":\"https:\\\/\\\/foodstory.es\\\/el-culebron-sobre-la-fatidica-promocion-de-red-lobsteraun-colea\\\/\",\"name\":\"El culebr\u00f3n sobre la \u00a0fat\u00eddica promoci\u00f3n de Red Lobster,aun colea - Food Story\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/foodstory.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/foodstory.es\\\/el-culebron-sobre-la-fatidica-promocion-de-red-lobsteraun-colea\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/foodstory.es\\\/el-culebron-sobre-la-fatidica-promocion-de-red-lobsteraun-colea\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/foodstory.es\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/cartel-d-ered-lobster.jpg\",\"datePublished\":\"2026-09-01T16:50:06+00:00\",\"dateModified\":\"2026-09-01T16:50:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/foodstory.es\\\/el-culebron-sobre-la-fatidica-promocion-de-red-lobsteraun-colea\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/foodstory.es\\\/el-culebron-sobre-la-fatidica-promocion-de-red-lobsteraun-colea\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/foodstory.es\\\/el-culebron-sobre-la-fatidica-promocion-de-red-lobsteraun-colea\\\/#primaryimage\",\"url\":\"https:\\\/\\\/foodstory.es\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/cartel-d-ered-lobster.jpg\",\"contentUrl\":\"https:\\\/\\\/foodstory.es\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/cartel-d-ered-lobster.jpg\",\"width\":767,\"height\":420},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/foodstory.es\\\/el-culebron-sobre-la-fatidica-promocion-de-red-lobsteraun-colea\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/foodstory.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El culebr\u00f3n sobre la \u00a0fat\u00eddica promoci\u00f3n de Red Lobster,aun colea\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/foodstory.es\\\/#website\",\"url\":\"https:\\\/\\\/foodstory.es\\\/\",\"name\":\"Food Story\",\"description\":\"Visionando el futuro sin olvidar el pasado\",\"publisher\":{\"@id\":\"https:\\\/\\\/foodstory.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/foodstory.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/foodstory.es\\\/#organization\",\"name\":\"Food Story\",\"url\":\"https:\\\/\\\/foodstory.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/foodstory.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/foodstory.es\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/LOGO-Food-Story.png\",\"contentUrl\":\"https:\\\/\\\/foodstory.es\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/LOGO-Food-Story.png\",\"width\":800,\"height\":800,\"caption\":\"Food Story\"},\"image\":{\"@id\":\"https:\\\/\\\/foodstory.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/foodstory.es\\\/#\\\/schema\\\/person\\\/9f90bee5e60ba1bf8d3f286132644e1e\",\"name\":\"eloi\",\"sameAs\":[\"http:\\\/\\\/foodstory.es\"],\"url\":\"https:\\\/\\\/foodstory.es\\\/ca\\\/author\\\/eloi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El culebr\u00f3n sobre la \u00a0fat\u00eddica promoci\u00f3n de Red Lobster,aun colea - Food Story","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/foodstory.es\/ca\/el-culebron-sobre-la-fatidica-promocion-de-red-lobsteraun-colea\/","og_locale":"ca_ES","og_type":"article","og_title":"El culebr\u00f3n sobre la \u00a0fat\u00eddica promoci\u00f3n de Red Lobster,aun colea - Food Story","og_description":"Seg\u00fan&nbsp; Joe Guszkowski, redactor senior de Business Restaurant,el exaccionista de Red Lobster, Thai Union Group, afirma que no es responsable de la desastrosa promoci\u00f3n Ultimate Endless Shrimp de la cadena hace tres a\u00f1os. En un documento judicial presentado la semana pasada, el...","og_url":"https:\/\/foodstory.es\/ca\/el-culebron-sobre-la-fatidica-promocion-de-red-lobsteraun-colea\/","og_site_name":"Food Story","article_published_time":"2026-09-01T16:50:06+00:00","article_modified_time":"2026-09-01T16:50:10+00:00","og_image":[{"width":767,"height":420,"url":"https:\/\/foodstory.es\/wp-content\/uploads\/2024\/06\/cartel-d-ered-lobster.jpg","type":"image\/jpeg"}],"author":"eloi","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"eloi","Temps estimat de lectura":"5 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/foodstory.es\/el-culebron-sobre-la-fatidica-promocion-de-red-lobsteraun-colea\/#article","isPartOf":{"@id":"https:\/\/foodstory.es\/el-culebron-sobre-la-fatidica-promocion-de-red-lobsteraun-colea\/"},"author":{"name":"eloi","@id":"https:\/\/foodstory.es\/#\/schema\/person\/9f90bee5e60ba1bf8d3f286132644e1e"},"headline":"El culebr\u00f3n sobre la \u00a0fat\u00eddica promoci\u00f3n de Red Lobster,aun colea","datePublished":"2026-09-01T16:50:06+00:00","dateModified":"2026-09-01T16:50:10+00:00","mainEntityOfPage":{"@id":"https:\/\/foodstory.es\/el-culebron-sobre-la-fatidica-promocion-de-red-lobsteraun-colea\/"},"wordCount":980,"publisher":{"@id":"https:\/\/foodstory.es\/#organization"},"image":{"@id":"https:\/\/foodstory.es\/el-culebron-sobre-la-fatidica-promocion-de-red-lobsteraun-colea\/#primaryimage"},"thumbnailUrl":"https:\/\/foodstory.es\/wp-content\/uploads\/2024\/06\/cartel-d-ered-lobster.jpg","articleSection":["RESTAURACI\u00d3N COMERCIAL"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/foodstory.es\/el-culebron-sobre-la-fatidica-promocion-de-red-lobsteraun-colea\/","url":"https:\/\/foodstory.es\/el-culebron-sobre-la-fatidica-promocion-de-red-lobsteraun-colea\/","name":"El culebr\u00f3n sobre la \u00a0fat\u00eddica promoci\u00f3n de Red Lobster,aun colea - Food Story","isPartOf":{"@id":"https:\/\/foodstory.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/foodstory.es\/el-culebron-sobre-la-fatidica-promocion-de-red-lobsteraun-colea\/#primaryimage"},"image":{"@id":"https:\/\/foodstory.es\/el-culebron-sobre-la-fatidica-promocion-de-red-lobsteraun-colea\/#primaryimage"},"thumbnailUrl":"https:\/\/foodstory.es\/wp-content\/uploads\/2024\/06\/cartel-d-ered-lobster.jpg","datePublished":"2026-09-01T16:50:06+00:00","dateModified":"2026-09-01T16:50:10+00:00","breadcrumb":{"@id":"https:\/\/foodstory.es\/el-culebron-sobre-la-fatidica-promocion-de-red-lobsteraun-colea\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/foodstory.es\/el-culebron-sobre-la-fatidica-promocion-de-red-lobsteraun-colea\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/foodstory.es\/el-culebron-sobre-la-fatidica-promocion-de-red-lobsteraun-colea\/#primaryimage","url":"https:\/\/foodstory.es\/wp-content\/uploads\/2024\/06\/cartel-d-ered-lobster.jpg","contentUrl":"https:\/\/foodstory.es\/wp-content\/uploads\/2024\/06\/cartel-d-ered-lobster.jpg","width":767,"height":420},{"@type":"BreadcrumbList","@id":"https:\/\/foodstory.es\/el-culebron-sobre-la-fatidica-promocion-de-red-lobsteraun-colea\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/foodstory.es\/"},{"@type":"ListItem","position":2,"name":"El culebr\u00f3n sobre la \u00a0fat\u00eddica promoci\u00f3n de Red Lobster,aun colea"}]},{"@type":"WebSite","@id":"https:\/\/foodstory.es\/#website","url":"https:\/\/foodstory.es\/","name":"Food Story","description":"Visionant el futur sense oblidar el passat","publisher":{"@id":"https:\/\/foodstory.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/foodstory.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/foodstory.es\/#organization","name":"Food Story","url":"https:\/\/foodstory.es\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/foodstory.es\/#\/schema\/logo\/image\/","url":"https:\/\/foodstory.es\/wp-content\/uploads\/2024\/01\/LOGO-Food-Story.png","contentUrl":"https:\/\/foodstory.es\/wp-content\/uploads\/2024\/01\/LOGO-Food-Story.png","width":800,"height":800,"caption":"Food Story"},"image":{"@id":"https:\/\/foodstory.es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/foodstory.es\/#\/schema\/person\/9f90bee5e60ba1bf8d3f286132644e1e","name":"eloi","sameAs":["http:\/\/foodstory.es"],"url":"https:\/\/foodstory.es\/ca\/author\/eloi\/"}]}},"taxonomy_info":{"category":[{"value":7,"label":"RESTAURACI\u00d3N COMERCIAL"}]},"featured_image_src_large":["https:\/\/foodstory.es\/wp-content\/uploads\/2024\/06\/cartel-d-ered-lobster.jpg",767,420,false],"author_info":{"display_name":"eloi","author_link":"https:\/\/foodstory.es\/ca\/author\/eloi\/"},"comment_info":0,"category_info":[{"term_id":7,"name":"RESTAURACI\u00d3N COMERCIAL","slug":"restauracion-comercial","term_group":0,"term_taxonomy_id":7,"taxonomy":"category","description":"","parent":0,"count":145,"filter":"raw","term_order":"0","cat_ID":7,"category_count":145,"category_description":"","cat_name":"RESTAURACI\u00d3N COMERCIAL","category_nicename":"restauracion-comercial","category_parent":0}],"tag_info":false,"_links":{"self":[{"href":"https:\/\/foodstory.es\/ca\/wp-json\/wp\/v2\/posts\/3397","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/foodstory.es\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/foodstory.es\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/foodstory.es\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/foodstory.es\/ca\/wp-json\/wp\/v2\/comments?post=3397"}],"version-history":[{"count":1,"href":"https:\/\/foodstory.es\/ca\/wp-json\/wp\/v2\/posts\/3397\/revisions"}],"predecessor-version":[{"id":3398,"href":"https:\/\/foodstory.es\/ca\/wp-json\/wp\/v2\/posts\/3397\/revisions\/3398"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/foodstory.es\/ca\/wp-json\/wp\/v2\/media\/1659"}],"wp:attachment":[{"href":"https:\/\/foodstory.es\/ca\/wp-json\/wp\/v2\/media?parent=3397"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/foodstory.es\/ca\/wp-json\/wp\/v2\/categories?post=3397"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/foodstory.es\/ca\/wp-json\/wp\/v2\/tags?post=3397"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}